{"id":467,"date":"2023-04-03T12:48:49","date_gmt":"2023-04-03T10:48:49","guid":{"rendered":"https:\/\/fbbsburkina.com\/?p=467"},"modified":"2023-04-03T19:48:07","modified_gmt":"2023-04-03T17:48:07","slug":"cooperation-sportive-japon-burkina-baseball-le-sport-qui-veut-tutoyer-les-sommets","status":"publish","type":"post","link":"https:\/\/fbbsburkina.com\/index.php\/2023\/04\/03\/cooperation-sportive-japon-burkina-baseball-le-sport-qui-veut-tutoyer-les-sommets\/","title":{"rendered":"Coop\u00e9ration sportive Japon\/Burkina : Baseball, le sport qui veut tutoyer les sommets"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i0.wp.com\/www.sidwaya.info\/wp-content\/uploads\/2023\/03\/baseball3.gif?fit=770%2C462&amp;ssl=1\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.sidwaya.info\/wp-content\/uploads\/2023\/03\/baseball3.gif?resize=696%2C418&amp;ssl=1\" alt=\"\" title=\"baseball3\"\/><\/a><figcaption>Le Japon fournit r\u00e9guli\u00e8rement du mat\u00e9riel \u00e0 la FBBS pour le d\u00e9veloppement du baseball au Burkina.<\/figcaption><\/figure>\n\n\n\n<p>Le Burkina Faso est un pays o\u00f9 le cyclisme, l\u2019athl\u00e9tisme et surtout le football constituent les sports les plus pratiqu\u00e9s et appr\u00e9ci\u00e9s de la population.<\/p>\n\n\n\n<p>Cependant, depuis cinq ans, une autre discipline m\u00e9connue du public, il y a une d\u00e9cennie, pointe \u00e0 l\u2019horizon avec ses performances non n\u00e9gligeables: le baseball.<\/p>\n\n\n\n<p>Ce sport qui devient de plus en plus populaire est l\u2019\u0153uvre de l\u2019excellente collaboration depuis 2008 entre la F\u00e9d\u00e9ration burkinab\u00e8 de baseball et l\u2019ambassade du Japon au Burkina.<\/p>\n\n\n\n<p>Cette information, tr\u00e8s peu de Burkinab\u00e8 la connaissent, \u00e0 part les amoureux de la discipline. Le Burkina Faso est l\u2019actuel 50e mondial au classement du Baseball world Rankings 2022 Men\u2019s en date du 31 d\u00e9cembre 2022. Ce classement de la World Baseball and Softball Confederation place le pays des Hommes int\u00e8gres au 4e rang africain derri\u00e8re l\u2019Afrique du Sud, 1er en Afrique (25e mondial), l\u2019Ouganda 2e(41e mondial) et le Zimbabwe 3e(46e mondial).<\/p>\n\n\n\n<p>Certes, avec 61 points, le Burkina Faso se classe tr\u00e8s loin des 4179 points de l\u2019intouchable Japon, premier mondial de la discipline. Mais force est de reconnaitre que ces performances, \u00e0 ne surtout pas minimiser dans un pays o\u00f9 la discipline est quasi-m\u00e9connue, sont l\u2019\u0153uvre de l\u2019excellent parcours des Etalons lors des championnats d\u2019Afrique de baseball en 2019 en Afrique du Sud.<\/p>\n\n\n\n<p>En effet, le Burkina Faso a gagn\u00e9 ses lettres de noblesse dans le concert des nations de baseball, d\u2019abord lors des \u00e9liminatoires r\u00e9gionales au Ghana o\u00f9 il a occup\u00e9 la premi\u00e8re place devant le pays h\u00f4te et le Nig\u00e9ria.<\/p>\n\n\n\n<p>Il s\u2019\u00e9tait ensuite hiss\u00e9 quelques mois plus tard \u00e0 la 4e place des premiers championnats d\u2019Afrique de baseball, qualificatifs pour les Jeux Olympiques de Tokyo 2020.<\/p>\n\n\n\n<p>Si le Burkina Faso peut \u00eatre consid\u00e9r\u00e9 de nos jours comme un pays de baseball en Afrique de l\u2019ouest et une r\u00e9f\u00e9rence sur le continent, il le doit \u00e0 l\u2019excellent travail, depuis 2004, des jeunes volontaires (JOCV) de l\u2019Agence japonaise de coop\u00e9ration internationale (JICA).<\/p>\n\n\n\n<p>\u00ab Depuis la cr\u00e9ation de la F\u00e9d\u00e9ration burkinab\u00e8 de baseball et de softball en d\u00e9cembre 2004 nous avons b\u00e9n\u00e9fici\u00e9 de l\u2019appui des volontaires japonais qui nous ont appuy\u00e9s dans la formation des joueurs, des coachs, des scoreurs et de tous les acteurs du baseball burkinab\u00e8 \u00bb, reconnait le pr\u00e9sident de la F\u00e9d\u00e9ration burkinab\u00e8 de baseball et softball, Ibrahima Sibor\u00e9.<\/p>\n\n\n\n<p>Le d\u00e9ploiement de volontaires \u00e0 Koudougou et Ouagadougou, poursuit-il, a permis de renforcer les capacit\u00e9s des clubs de baseball existants dans ces deux villes.<\/p>\n\n\n\n<p>\u00ab Si ces deux villes ont un niveau de baseball tr\u00e8s \u00e9lev\u00e9, c\u2019est gr\u00e2ce aux volontaires de la JICA. Si vous remarquez, dans nos diff\u00e9rents championnats nationaux, Koudougou et Ouagadougou se hissent r\u00e9guli\u00e8rement en finale \u00bb, r\u00e9v\u00e8le Ibrahima Sibor\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le travail titanesque des volontaires Japonais<\/strong><\/h3>\n\n\n\n<p>En effet, entre 2008 et 2018, huit volontaires Japonais ont assist\u00e9 techniquement la F\u00e9d\u00e9ration burkinab\u00e8 de baseball et de softball (FBBS) ainsi que les clubs burkinab\u00e8. L\u2019un d\u2019entre eux a marqu\u00e9 et continue de faire la tr\u00e8s jeune histoire du Burkina Faso dans la pratique du baseball : Yuta Deai.<\/p>\n\n\n\n<p>Les visages de tous les acteurs du baseball de m\u00eame que les joueurs s\u2019illuminent automatiquement \u00e0 l\u2019\u00e9vocation de son nom. \u00ab Yuta est celui qui a boost\u00e9 le niveau du baseball burkinab\u00e8 \u00e0 un niveau tr\u00e8s \u00e9lev\u00e9 \u00bb, s\u2019exclame Ibrahima Sibor\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_64767\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.sidwaya.info\/wp-content\/uploads\/2023\/03\/baseball.gif?resize=696%2C443&amp;ssl=1\" alt=\"\" class=\"wp-image-64767\"\/><figcaption><strong>Les Etalons baseballeurs ont termin\u00e9 \u00e0 la 4e place des championnats d\u2019Afrique en 2019, en Afrique du Sud.<\/strong><\/figcaption><\/figure>\n\n\n\n<p>L\u2019ancien directeur technique national (2004-2016), Boukar\u00e9 Sawadogo embouche la m\u00eame trompette en indiquant qu\u2019il a \u00e9t\u00e9 le premier volontaire envoy\u00e9 par la JICA en 2008 pour \u00e9pauler la F\u00e9d\u00e9ration.<\/p>\n\n\n\n<p>\u00ab Nous avons d\u00e9but\u00e9 l\u2019implantation du baseball au Burkina en 1999. Nous avons donc commenc\u00e9 \u00e0 participer en 2001 \u00e0 des comp\u00e9titions. Lors des comp\u00e9titions nous avons rencontr\u00e9 des volontaires japonais qui participaient \u00e9galement aux tournois. Nous avons sollicit\u00e9 un volontaire pour nous appuyer, mais \u00e0 l\u2019\u00e9poque la F\u00e9d\u00e9ration de baseball n\u2019existait pas, c\u2019\u00e9tait un peu compliqu\u00e9. Mais les choses se sont r\u00e9gl\u00e9es \u00e0 la cr\u00e9ation de la F\u00e9d\u00e9ration \u00bb, raconte Sawadogo qui souligne que l\u2019apport de Yuta, depuis 2008 dans la promotion du baseball au Burkina Faso est inestimable.<\/p>\n\n\n\n<p>La belle histoire entre Yuta et le Burkina Faso commence en mars 2008 lorsque le Nippon d\u00e9barque \u00e0 Ouagadougou comme volontaire \u00e0 la JICA. Il est passionn\u00e9 de baseball depuis l\u2019enfance, mais trouve au Burkina Faso une discipline presque m\u00e9connue.<\/p>\n\n\n\n<p>Au d\u00e9but de son volontariat, il apprenait les fondamentaux de la discipline \u00e0 des gar\u00e7ons et certains anciens apprenants dans des quartiers de la ville de Ouagadougou. Les activit\u00e9s de Yuta se formalisent plus tard avec son soutien \u00e0 la F\u00e9d\u00e9ration burkinab\u00e8 de baseball.<\/p>\n\n\n\n<p>\u00ab Ouagadougou comptait trois \u00e9quipes \u00e0 l\u2019\u00e9poque. Cependant, il n\u2019y avait pas d\u2019environnement de baseball (entra\u00eeneur ou arbitre qui connaissait les r\u00e8gles du baseball, le terrain, les \u00e9quipements). La mission attribu\u00e9e par la F\u00e9d\u00e9ration de baseball est de renforcer les trois \u00e9quipes existantes, d\u2019augmenter le nombre de joueurs et d\u2019\u00e9quipements, d\u2019organiser des tournois, de rendre le baseball populaire. La mission \u00e9tait de d\u00e9velopper tout ce qui touche au baseball \u00bb, r\u00e9v\u00e8le Yuta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>L\u2019incontournable Yuta Deai<\/strong><\/h3>\n\n\n\n<p>Il commence les week-ends \u00e0 coacher les \u00e9quipes qui existaient dans la ville de Ouagadougou, en leur prodiguant des conseils pour les rendre meilleures. Mais la mission du volontaire s\u2019av\u00e8re rude et il se rend tr\u00e8s vite compte qu\u2019il doit changer le fusil d\u2019\u00e9paule.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_64770\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.sidwaya.info\/wp-content\/uploads\/2023\/03\/baseball4.gif?resize=696%2C457&amp;ssl=1\" alt=\"\" class=\"wp-image-64770\"\/><figcaption><strong>Les clubs disposent d\u00e9sormais d\u2019un terrain de baseball gr\u00e2ce \u00e0 un don de l\u2019ambassade du Japon.<\/strong><\/figcaption><\/figure>\n\n\n\n<p>La plupart des joueurs trainaient des lacunes qui \u00e9taient difficiles \u00e0 corriger. \u00ab Alors, j\u2019ai r\u00e9uni des enfants qui ne connaissaient rien du baseball et j\u2019ai commenc\u00e9 \u00e0 leur parler de la discipline. Je trouvais plus facile d\u2019apprendre la bonne pratique du baseball si les enfants n\u2019ont pas une id\u00e9e de ce que c\u2019est. J\u2019ai pass\u00e9 le maximum de temps possible avec les enfants, donc tous les jours, pas de temps en temps. Apr\u00e8s cela, l\u2019\u00e9quipe de Gounghin est devenue un cas mod\u00e8le qui s\u2019est r\u00e9pandu dans divers endroits du pays \u00bb, d\u00e9taille-t-il.<\/p>\n\n\n\n<p>Yuta ach\u00e8ve son s\u00e9jour comme volontaire japonais en mars 2010 et retourne au bercail. Pour autant, il ne veut pas abandonner les graines qu\u2019il a sem\u00e9es du c\u00f4t\u00e9 de Gounghin.<\/p>\n\n\n\n<p>Dans son pays natal, il recherche des partenaires pour accueillir des joueurs burkinab\u00e8 et en mars 2012, une \u00e9quipe semi-professionnelle de Kochi, Fighting Dogs, accepte de les accueillir.<\/p>\n\n\n\n<p>Cette tradition va se perp\u00e9tuer chaque ann\u00e9e avec de fr\u00e9quents s\u00e9jours de joueurs au pays du Soleil Levant, qui sera renforc\u00e9 en avril 2017 avec la cr\u00e9ation de son centre, l\u2019Acad\u00e9mie de baseball \u00e0 Hokkaido devenue une structure qui accueille les sportifs burkinab\u00e8.<\/p>\n\n\n\n<p>Aussi, la 4e place du Burkina Faso au championnat d\u2019Afrique de 2019 en Afrique du Sud est \u00e0 mettre, en grande partie, \u00e0 l\u2019actif de l\u2019engagement de Yuta, le s\u00e9lectionneur tr\u00e8s attentionn\u00e9 des Etalons (il n\u2019h\u00e9site pas \u00e0 mettre la main \u00e0 la poche pour financer certains voyages de l\u2019\u00e9quipe nationale).<\/p>\n\n\n\n<p>\u00ab Lorsqu\u2019il y a une comp\u00e9tition internationale, toute l\u2019\u00e9quipe se rend au Japon pour un stage. Dans le cadre des \u00e9liminatoires des JO 2020, l\u2019\u00e9quipe burkinab\u00e8 s\u2019est rendue au Japon gr\u00e2ce \u00e0 Yuta \u00bb, mentionne Ibrahim Sibor\u00e9.<\/p>\n\n\n\n<p>Le Burkina Faso est aujourd\u2019hui l\u2019une des premi\u00e8res nations de baseball, appuie Boukar\u00e9 Sawadogo, gr\u00e2ce \u00e0 l\u2019\u00e9quipe des moins de 12 ans que son coach national a mont\u00e9e en 2009.<\/p>\n\n\n\n<p>\u00ab Ils avaient 10 \u00e0 11 ans \u00e0 l\u2019\u00e9poque. M\u00eame lorsque Yuta est retourn\u00e9 au Japon, il leur envoyait par vid\u00e9o des exercices sp\u00e9cifiques pour poursuivre leur progression. Et pendant les vacances il faisait venir certains au Japon pour des s\u00e9jours de 2 \u00e0 3 mois \u00bb, se rem\u00e9more Boukar\u00e9 Sawadogo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Lassina Sanfo, la fiert\u00e9 du baseball burkinab\u00e8<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_64768\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.sidwaya.info\/wp-content\/uploads\/2023\/03\/baseball2.gif?resize=300%2C197&amp;ssl=1\" alt=\"\" class=\"wp-image-64768\"\/><figcaption><strong>Yuta, \u00e0 l\u2019\u00e9poque en compagnie de ses jeunes joueurs du quartier Gounghin.<\/strong><\/figcaption><\/figure>\n\n\n\n<p>La figure de proue de cette \u00e9quipe pr\u00e9sentement est sans conteste Lassina Sanfo.<\/p>\n\n\n\n<p>Joueur professionnel depuis 2015 et actuel capitaine de son \u00e9quipe, Kochi Fighting Dogs, le jeune Burkinab\u00e8 a \u00e9t\u00e9 d\u00e9sign\u00e9 meilleur joueur de champ de son championnat pour la saison 2020-2021, dans la ligue de SHIKOKU ISLAND LEAGUE au Japon.<\/p>\n\n\n\n<p>\u00ab J\u2019ai connu le baseball avec Yuta en 2008. En 2013, je suis arriv\u00e9 \u00e0 Hokkaido, pr\u00e9cis\u00e9ment dans le village de Furano chez Yuta, pour me former. Tout s\u2019est bien pass\u00e9 gr\u00e2ce aux encouragements de tous les fans dans la ville de Kochi. Yuta est l\u2019une des personnes les plus importantes dans le d\u00e9veloppement du baseball au Burkina Faso \u00bb, estime le joueur de Kochi Fighting Dogs, Lassina Sanfo.<\/p>\n\n\n\n<p>Tous les acteurs du baseball burkinab\u00e8 sont unanimes: Yuta est \u00e0 la base de la carri\u00e8re professionnelle que m\u00e8ne Lassina Sanfo au Japon et qui sera peut-\u00eatre rejoint tr\u00e8s bient\u00f4t par Hamidou Kafando, le capitaine des Etalons.<\/p>\n\n\n\n<p>Pour l\u2019ex-volontaire, cet engagement provient de sa passion pour le baseball.<\/p>\n\n\n\n<p>\u00ab Ma passion pour le baseball est issue de la curiosit\u00e9. Raison pour laquelle je continue \u00e0 faire avancer l\u2019histoire du baseball au Burkina Faso avec les jeunes burkinab\u00e8 engag\u00e9s. J\u2019aime voir l\u2019impossible devenir possible. J\u2019appr\u00e9cie voir les r\u00eaves se r\u00e9aliser. Je ne mets pas de limites aux potentiels humains \u00bb, justifie-t-il, un brin philosophe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le complexe sportif, la fiert\u00e9 des acteurs du baseball<\/strong><\/h3>\n\n\n\n<p>L\u2019engagement sans faille de Yuta, les appuis permanents de la JICA et de l\u2019ambassade du Japon, de l\u2019avis du pr\u00e9sident de la F\u00e9d\u00e9ration, Ibrahim Sibor\u00e9, ne peuvent qu\u2019offrir un avenir meilleur au baseball burkinab\u00e8.<\/p>\n\n\n\n<p>Une trentaine de clubs sont pr\u00e9sentement affili\u00e9s \u00e0 la F\u00e9d\u00e9ration et les nombreux dons de la JICA ainsi que de l\u2019ambassade en mat\u00e9riels augmentent leurs performances.<\/p>\n\n\n\n<p>\u00ab C\u2019est gr\u00e2ce \u00e0 ces dons que nous continuons \u00e0 pratiquer le baseball au Burkina. Nous sommes en voie de recevoir un gros lot de mat\u00e9riel gr\u00e2ce encore \u00e0 Yuta. Il nous envoie un conteneur de mat\u00e9riel par le biais du club Chunichi Dragons, un autre grand club du Japon \u00bb, appr\u00e9cie Ibrahima Sibor\u00e9.<\/p>\n\n\n\n<p>Et que dire du complexe sportif avec terrain de baseball inaugur\u00e9 en fin f\u00e9vrier dernier ! Selon Ibrahim Sibor\u00e9, ce don du Japon \u00e0 plus de 50 millions FCFA, enl\u00e8ve une grosse \u00e9pine \u00e0 leur pied.<\/p>\n\n\n\n<p>\u00ab Disposer d\u2019un terrain o\u00f9 on peut tracer et avoir les dimensions selon les normes internationales permettra d\u00e9j\u00e0 de nous entrainer et nous pr\u00e9parer aux comp\u00e9titions internationales. Il est difficile de pratiquer son sport aux heures voulues lorsque l\u2019on ne dispose pas d\u2019un terrain \u00bb, se f\u00e9licite-il.<\/p>\n\n\n\n<p>La FBBS, \u00e0 travers son pr\u00e9sident, dit vouloir aller tutoyer les sommets dans un proche avenir. Pour ce faire, il est n\u00e9cessaire, selon Ibrahim Sibor\u00e9, de cr\u00e9er une ligue professionnelle pour permettre aux clubs de se constituer en clubs semi-professionnels.<\/p>\n\n\n\n<p>L\u2019objectif est de permettre aux diff\u00e9rentes \u00e9quipes nationales d\u2019avoir un niveau international afin que les joueurs puissent rejoindre des formations hupp\u00e9es.<\/p>\n\n\n\n<p>Yuta, lui, conseille la cr\u00e9ation de \u00ab ligues sportives \u00bb pour que \u00ab les enfants et les adultes puissent nourrir un id\u00e9al \u00bb. En attendant, l\u2019ancien volontaire japonais n\u2019est pas pr\u00eat \u00e0 l\u00e2cher le Burkina Faso et ses baseballeurs.<\/p>\n\n\n\n<p>\u00ab J\u2019ai beaucoup appris au Burkina Faso. J\u2019ai appris la joie de transformer 0 en 1. J\u2019ai appris le plaisir de transformer 1 en 2. Le Burkinab\u00e8 aura un bel avenir s\u2019il arrive \u00e0 nourrir la passion des gens. Le Burkinab\u00e8 a beaucoup de potentiel. Il n\u2019y a pas que le baseball. Mon r\u00eave est d\u2019\u00e9largir les possibilit\u00e9s des Burkinab\u00e8 \u00bb, conclut-il.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Un article extrait de Sidwaya du 31 mars 20023, r\u00e9dig\u00e9 par M. <strong>Si\u00e9 Simplice HIEN<\/strong>, journaliste \u00e0 Sidwaya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Burkina Faso est un pays o\u00f9 le cyclisme, l\u2019athl\u00e9tisme et surtout le football constituent les sports les plus pratiqu\u00e9s et appr\u00e9ci\u00e9s de la population. Cependant, depuis cinq ans, une autre discipline m\u00e9connue du public, il y a une d\u00e9cennie, pointe \u00e0 l\u2019horizon avec ses performances non n\u00e9gligeables: le baseball. Ce sport qui devient de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":470,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14,16,15],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/fbbsburkina.com\/wp-content\/uploads\/2023\/04\/1.webp","_links":{"self":[{"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/posts\/467"}],"collection":[{"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/comments?post=467"}],"version-history":[{"count":1,"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/posts\/467\/revisions"}],"predecessor-version":[{"id":468,"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/posts\/467\/revisions\/468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/media\/470"}],"wp:attachment":[{"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/media?parent=467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/categories?post=467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbbsburkina.com\/index.php\/wp-json\/wp\/v2\/tags?post=467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}